{"id":9,"count":25,"description":"","link":"https:\/\/dtrees.com\/en\/category\/nicht-kategorisiert-de\/","name":"Nicht kategorisiert","slug":"nicht-kategorisiert-de","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/dtrees.com\/en\/wp-json\/wp\/v2\/categories\/9","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dtrees.com\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/dtrees.com\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/dtrees.com\/en\/wp-json\/wp\/v2\/posts?categories=9"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}